{"id":4273,"date":"2023-11-14T15:25:46","date_gmt":"2023-11-14T14:25:46","guid":{"rendered":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA.png"},"modified":"2023-11-14T15:25:46","modified_gmt":"2023-11-14T14:25:46","slug":"i-jornades-memoria","status":"inherit","type":"attachment","link":"https:\/\/lasenia.cat\/web\/i-jornades-memoria\/","title":{"rendered":"I JORNADES MEMO\u0300RIA"},"author":6,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout"},"class_list":["post-4273","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-300x200.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-300x200.png 300w, https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-1024x683.png 1024w, https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-768x512.png 768w, https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-1536x1024.png 1536w, https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA.png 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":2048,"height":1365,"file":"2023\/11\/I-JORNADES-MEMORIA.png","filesize":3699685,"sizes":{"medium":{"file":"I-JORNADES-MEMORIA-300x200.png","width":300,"height":200,"filesize":88171,"mime_type":"image\/png","source_url":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-300x200.png"},"large":{"file":"I-JORNADES-MEMORIA-1024x683.png","width":1024,"height":683,"filesize":871882,"mime_type":"image\/png","source_url":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-1024x683.png"},"thumbnail":{"file":"I-JORNADES-MEMORIA-150x150.png","width":150,"height":150,"filesize":36708,"mime_type":"image\/png","source_url":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-150x150.png"},"medium_large":{"file":"I-JORNADES-MEMORIA-768x512.png","width":768,"height":512,"filesize":503089,"mime_type":"image\/png","source_url":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-768x512.png"},"1536x1536":{"file":"I-JORNADES-MEMORIA-1536x1024.png","width":1536,"height":1024,"filesize":1919809,"mime_type":"image\/png","source_url":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-1536x1024.png"},"colormag-highlighted-post":{"file":"I-JORNADES-MEMORIA-392x272.png","width":392,"height":272,"filesize":147242,"mime_type":"image\/png","source_url":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-392x272.png"},"colormag-featured-post-medium":{"file":"I-JORNADES-MEMORIA-390x205.png","width":390,"height":205,"filesize":109213,"mime_type":"image\/png","source_url":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-390x205.png"},"colormag-featured-post-small":{"file":"I-JORNADES-MEMORIA-130x90.png","width":130,"height":90,"filesize":20412,"mime_type":"image\/png","source_url":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-130x90.png"},"colormag-featured-image":{"file":"I-JORNADES-MEMORIA-800x445.png","width":800,"height":445,"filesize":438790,"mime_type":"image\/png","source_url":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-800x445.png"},"colormag-default-news":{"file":"I-JORNADES-MEMORIA-150x150.png","width":150,"height":150,"filesize":36708,"mime_type":"image\/png","source_url":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-150x150.png"},"colormag-featured-image-large":{"file":"I-JORNADES-MEMORIA-1400x600.png","width":1400,"height":600,"filesize":956703,"mime_type":"image\/png","source_url":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA-1400x600.png"},"full":{"file":"I-JORNADES-MEMORIA.png","width":2048,"height":1365,"mime_type":"image\/png","source_url":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/lasenia.cat\/web\/wp-content\/uploads\/2023\/11\/I-JORNADES-MEMORIA.png","_links":{"self":[{"href":"https:\/\/lasenia.cat\/web\/wp-json\/wp\/v2\/media\/4273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasenia.cat\/web\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/lasenia.cat\/web\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/lasenia.cat\/web\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasenia.cat\/web\/wp-json\/wp\/v2\/comments?post=4273"}]}}